{"id":3607,"date":"2019-03-11T20:34:08","date_gmt":"2019-03-11T20:34:08","guid":{"rendered":"http:\/\/www.meridian.ba\/?post_type=product&#038;p=3607"},"modified":"2020-09-20T19:05:52","modified_gmt":"2020-09-20T19:05:52","slug":"gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase","status":"publish","type":"product","link":"https:\/\/www.meridian.ba\/en\/proizvodi\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\/","title":{"rendered":"Beverage crates 284x413x248mm \u2013 24x bottle crates"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Plastic beverage crates with 24x dividers<\/p>\n<p><strong>Model No: 4524-SK\u00a0<\/strong><\/p>","protected":false},"featured_media":3602,"template":"","meta":[],"product_brand":[],"product_cat":[193,332,133],"product_tag":[195,196,194],"class_list":["post-3607","product","type-product","status-publish","has-post-thumbnail","product_cat-gajbe-za-pice","product_cat-gajbe-za-skladistenje","product_cat-plasticne-gajbe","product_tag-bottle-crate","product_tag-crate-with-dividers","product_tag-gajbe-za-pice","pa_opcija-boja-bijela","pa_opcija-boja-crna","pa_opcija-boja-crvena","pa_opcija-boja-plava","pa_opcija-boja-siva","pa_opcija-boja-zelena","pa_opcija-boja-zuta","pa_unutrasnje-dimenzije-255-x-320-x-237-mm","entry","has-media","first","instock","shipping-taxable","purchasable","product-type-variable","has-product-nav","col","span_1_of_3","owp-content-center","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gajbe za pi\u0107e 284x413x248mm - 24x gajbe za fla\u0161e - Meridian Group<\/title>\n<meta name=\"description\" content=\"Plastic Beverage Crate With Different Color Option. Our Plastic Bottle Crates Have Different Dividers Option. Find Best Solution For Beverage Crates.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meridian.ba\/en\/proizvodi\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gajbe za pi\u0107e 284x413x248mm - 24x gajbe za fla\u0161e - Meridian Group\" \/>\n<meta property=\"og:description\" content=\"Plastic Beverage Crate With Different Color Option. Our Plastic Bottle Crates Have Different Dividers Option. Find Best Solution For Beverage Crates.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meridian.ba\/en\/proizvodi\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\/\" \/>\n<meta property=\"og:site_name\" content=\"Meridian Group\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/meridian.ba\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-20T19:05:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/03\/beverage-crate-800.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MeridianGroup2\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/en\\\/proizvodi\\\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\\\/\",\"url\":\"https:\\\/\\\/www.meridian.ba\\\/en\\\/proizvodi\\\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\\\/\",\"name\":\"Gajbe za pi\u0107e 284x413x248mm - 24x gajbe za fla\u0161e - Meridian Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/en\\\/proizvodi\\\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/en\\\/proizvodi\\\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meridian.ba\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/beverage-crate-800.jpg\",\"datePublished\":\"2019-03-11T20:34:08+00:00\",\"dateModified\":\"2020-09-20T19:05:52+00:00\",\"description\":\"Plastic Beverage Crate With Different Color Option. Our Plastic Bottle Crates Have Different Dividers Option. Find Best Solution For Beverage Crates.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/en\\\/proizvodi\\\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.meridian.ba\\\/en\\\/proizvodi\\\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/en\\\/proizvodi\\\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.meridian.ba\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/beverage-crate-800.jpg\",\"contentUrl\":\"https:\\\/\\\/www.meridian.ba\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/beverage-crate-800.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/en\\\/proizvodi\\\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.meridian.ba\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.meridian.ba\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gajbe za pi\u0107e 284x413x248mm &#8211; 24x gajbe za fla\u0161e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/#website\",\"url\":\"https:\\\/\\\/www.meridian.ba\\\/\",\"name\":\"Meridian Group\",\"description\":\"Rje\u0161enja pakovanja i skladi\u0161tenja\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.meridian.ba\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gajbe za pi\u0107e 284x413x248mm - 24x gajbe za fla\u0161e - Meridian Group","description":"Plastic Beverage Crate With Different Color Option. Our Plastic Bottle Crates Have Different Dividers Option. Find Best Solution For Beverage Crates.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meridian.ba\/en\/proizvodi\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\/","og_locale":"en_US","og_type":"article","og_title":"Gajbe za pi\u0107e 284x413x248mm - 24x gajbe za fla\u0161e - Meridian Group","og_description":"Plastic Beverage Crate With Different Color Option. Our Plastic Bottle Crates Have Different Dividers Option. Find Best Solution For Beverage Crates.","og_url":"https:\/\/www.meridian.ba\/en\/proizvodi\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\/","og_site_name":"Meridian Group","article_publisher":"https:\/\/www.facebook.com\/meridian.ba","article_modified_time":"2020-09-20T19:05:52+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/03\/beverage-crate-800.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MeridianGroup2","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.meridian.ba\/en\/proizvodi\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\/","url":"https:\/\/www.meridian.ba\/en\/proizvodi\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\/","name":"Gajbe za pi\u0107e 284x413x248mm - 24x gajbe za fla\u0161e - Meridian Group","isPartOf":{"@id":"https:\/\/www.meridian.ba\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.meridian.ba\/en\/proizvodi\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\/#primaryimage"},"image":{"@id":"https:\/\/www.meridian.ba\/en\/proizvodi\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/03\/beverage-crate-800.jpg","datePublished":"2019-03-11T20:34:08+00:00","dateModified":"2020-09-20T19:05:52+00:00","description":"Plastic Beverage Crate With Different Color Option. Our Plastic Bottle Crates Have Different Dividers Option. Find Best Solution For Beverage Crates.","breadcrumb":{"@id":"https:\/\/www.meridian.ba\/en\/proizvodi\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.meridian.ba\/en\/proizvodi\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.meridian.ba\/en\/proizvodi\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\/#primaryimage","url":"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/03\/beverage-crate-800.jpg","contentUrl":"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/03\/beverage-crate-800.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.meridian.ba\/en\/proizvodi\/gajbe-za-pice-284x413x248mm-24x-gajbe-za-flase\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.meridian.ba\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.meridian.ba\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Gajbe za pi\u0107e 284x413x248mm &#8211; 24x gajbe za fla\u0161e"}]},{"@type":"WebSite","@id":"https:\/\/www.meridian.ba\/#website","url":"https:\/\/www.meridian.ba\/","name":"Meridian Group","description":"Rje\u0161enja pakovanja i skladi\u0161tenja","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meridian.ba\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/product\/3607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/product\/3607\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/media\/3602"}],"wp:attachment":[{"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/media?parent=3607"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/product_brand?post=3607"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/product_cat?post=3607"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/product_tag?post=3607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}