{"id":7402,"date":"2019-12-07T15:18:50","date_gmt":"2019-12-07T15:18:50","guid":{"rendered":"https:\/\/www.meridijangroup.com\/?page_id=6900"},"modified":"2019-12-09T19:44:31","modified_gmt":"2019-12-09T19:44:31","slug":"fleksibilni-sigurnosni-znak","status":"publish","type":"page","link":"https:\/\/www.meridian.ba\/en\/fleksibilni-sigurnosni-znak\/","title":{"rendered":"Flexible Refuge Signs"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"7402\" class=\"elementor elementor-7402\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ce3b0d5 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"2ce3b0d5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c0fe85e\" data-id=\"4c0fe85e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7974640a elementor-widget elementor-widget-heading\" data-id=\"7974640a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Flexible Refuge Signs<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-375c5df7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"375c5df7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6f3f0f81\" data-id=\"6f3f0f81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64d48ee3 elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"64d48ee3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-chevron-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;layout&quot;:&quot;horizontal&quot;,&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-64d48ee3\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7426\"><a href=\"https:\/\/www.meridian.ba\/en\/fleksibilni-stub\/\" class=\"elementor-item\">Flexible Delineators<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7425\"><a href=\"https:\/\/www.meridian.ba\/en\/fleksibilni-sigurnosni-znak\/\" class=\"elementor-item\">Flexible Refuge Signs<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7418\"><a href=\"https:\/\/www.meridian.ba\/en\/gumeni-lezeci-policajac\/\" class=\"elementor-item\">Rubber Speed Ramps<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7420\"><a href=\"https:\/\/www.meridian.ba\/en\/katadiopter\/\" class=\"elementor-item\">Road Studs<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7428\"><a href=\"https:\/\/www.meridian.ba\/en\/konveksno-prometno-ogledalo\/\" class=\"elementor-item\">Convex Traffic Mirrors<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7419\"><a href=\"https:\/\/www.meridian.ba\/en\/parking-granicnik\/\" class=\"elementor-item\">Rubber Car Stoppers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-18480\"><a href=\"https:\/\/www.meridian.ba\/en\/parking-stalak-za-bicikle\/\" class=\"elementor-item\">Parking Stalak za Bicikle<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-18481\"><a href=\"https:\/\/www.meridian.ba\/en\/parking-stub-stubic-rampa\/\" class=\"elementor-item\">Parking stub<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7422\"><a href=\"https:\/\/www.meridian.ba\/en\/plasticni-lezeci-policajac\/\" class=\"elementor-item\">Plastic Speed Ramps<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7424\"><a href=\"https:\/\/www.meridian.ba\/en\/plasticni-konus\/\" class=\"elementor-item\">Plastic AD Cones<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7429\"><a href=\"https:\/\/www.meridian.ba\/en\/plasticni-stubovi\/\" class=\"elementor-item\">Caution Posts<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7423\"><a href=\"https:\/\/www.meridian.ba\/en\/plasticne-sigurne-ograde\/\" class=\"elementor-item\">Plastic Safety Barriers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7416\"><a href=\"https:\/\/www.meridian.ba\/en\/saobracajni-cunjevi\/\" class=\"elementor-item\">Traffic Cones<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7415\"><a href=\"https:\/\/www.meridian.ba\/en\/saobracajni-plasticni-znakovi\/\" class=\"elementor-item\">Traffic Plastic Signs<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7421\"><a href=\"https:\/\/www.meridian.ba\/en\/seperator-prometne-trake\/\" class=\"elementor-item\">Separator Prometne Trake<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7427\"><a href=\"https:\/\/www.meridian.ba\/en\/ugaoni-odbojnik\/\" class=\"elementor-item\">Corners Guards<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7417\"><a href=\"https:\/\/www.meridian.ba\/en\/upozoravajuce-ploce\/\" class=\"elementor-item\">Tactile Walking Surface<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-64d48ee3\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7426\"><a href=\"https:\/\/www.meridian.ba\/en\/fleksibilni-stub\/\" class=\"elementor-item\" tabindex=\"-1\">Flexible Delineators<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7425\"><a href=\"https:\/\/www.meridian.ba\/en\/fleksibilni-sigurnosni-znak\/\" class=\"elementor-item\" tabindex=\"-1\">Flexible Refuge Signs<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7418\"><a href=\"https:\/\/www.meridian.ba\/en\/gumeni-lezeci-policajac\/\" class=\"elementor-item\" tabindex=\"-1\">Rubber Speed Ramps<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7420\"><a href=\"https:\/\/www.meridian.ba\/en\/katadiopter\/\" class=\"elementor-item\" tabindex=\"-1\">Road Studs<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7428\"><a href=\"https:\/\/www.meridian.ba\/en\/konveksno-prometno-ogledalo\/\" class=\"elementor-item\" tabindex=\"-1\">Convex Traffic Mirrors<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7419\"><a href=\"https:\/\/www.meridian.ba\/en\/parking-granicnik\/\" class=\"elementor-item\" tabindex=\"-1\">Rubber Car Stoppers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-18480\"><a href=\"https:\/\/www.meridian.ba\/en\/parking-stalak-za-bicikle\/\" class=\"elementor-item\" tabindex=\"-1\">Parking Stalak za Bicikle<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-18481\"><a href=\"https:\/\/www.meridian.ba\/en\/parking-stub-stubic-rampa\/\" class=\"elementor-item\" tabindex=\"-1\">Parking stub<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7422\"><a href=\"https:\/\/www.meridian.ba\/en\/plasticni-lezeci-policajac\/\" class=\"elementor-item\" tabindex=\"-1\">Plastic Speed Ramps<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7424\"><a href=\"https:\/\/www.meridian.ba\/en\/plasticni-konus\/\" class=\"elementor-item\" tabindex=\"-1\">Plastic AD Cones<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7429\"><a href=\"https:\/\/www.meridian.ba\/en\/plasticni-stubovi\/\" class=\"elementor-item\" tabindex=\"-1\">Caution Posts<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7423\"><a href=\"https:\/\/www.meridian.ba\/en\/plasticne-sigurne-ograde\/\" class=\"elementor-item\" tabindex=\"-1\">Plastic Safety Barriers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7416\"><a href=\"https:\/\/www.meridian.ba\/en\/saobracajni-cunjevi\/\" class=\"elementor-item\" tabindex=\"-1\">Traffic Cones<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7415\"><a href=\"https:\/\/www.meridian.ba\/en\/saobracajni-plasticni-znakovi\/\" class=\"elementor-item\" tabindex=\"-1\">Traffic Plastic Signs<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7421\"><a href=\"https:\/\/www.meridian.ba\/en\/seperator-prometne-trake\/\" class=\"elementor-item\" tabindex=\"-1\">Separator Prometne Trake<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7427\"><a href=\"https:\/\/www.meridian.ba\/en\/ugaoni-odbojnik\/\" class=\"elementor-item\" tabindex=\"-1\">Corners Guards<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7417\"><a href=\"https:\/\/www.meridian.ba\/en\/upozoravajuce-ploce\/\" class=\"elementor-item\" tabindex=\"-1\">Tactile Walking Surface<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4c93a401\" data-id=\"4c93a401\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2578cf3f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2578cf3f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7488cd6d\" data-id=\"7488cd6d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42749b92 elementor-widget elementor-widget-image\" data-id=\"42749b92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/12\/UT-2601-Flexible-Refuge-Signs-600.jpg\" title=\"UT-2601-Flexible-Refuge-Signs-600\" alt=\"UT-2601-Flexible-Refuge-Signs-600\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3238df47\" data-id=\"3238df47\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4546db53 elementor-widget elementor-widget-heading\" data-id=\"4546db53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Order No: UT 2601<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32b91089 elementor-widget elementor-widget-text-editor\" data-id=\"32b91089\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Material:<\/strong>\u00a0TPU<\/p><p><strong>Lenght:<\/strong>\u00a0200 mm<\/p><p><strong>Width:<\/strong>\u00a030 mm<\/p><p><strong>Height:<\/strong>\u00a0850 mm<\/p><p><strong>Weight:<\/strong>\u00a02 kg\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3346f09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3346f09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f190d48\" data-id=\"f190d48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbe93ef elementor-widget elementor-widget-image\" data-id=\"bbe93ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/12\/UT-2606-Flexible-Refuge-Signs-600.jpg\" title=\"UT-2606-Flexible-Refuge-Signs-600\" alt=\"UT-2606-Flexible-Refuge-Signs-600\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-439e121\" data-id=\"439e121\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-800646f elementor-widget elementor-widget-heading\" data-id=\"800646f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Order No: UT 2606<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c00f55 elementor-widget elementor-widget-text-editor\" data-id=\"6c00f55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Material:<\/strong>\u00a0TPU<\/p><p><strong>Lenght:<\/strong>\u00a0315 mm<\/p><p><strong>Width:<\/strong>\u00a040 mm<\/p><p><strong>Height:<\/strong>\u00a01000 mm<\/p><p><strong>Weight:<\/strong>\u00a03,42 kg\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-62ae5f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62ae5f1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6e4dee5\" data-id=\"6e4dee5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-274d3a5 elementor-widget elementor-widget-image\" data-id=\"274d3a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/12\/UT-2605-Flexible-Refuge-Signs-600.jpg\" title=\"UT-2605-Flexible-Refuge-Signs-600\" alt=\"UT-2605-Flexible-Refuge-Signs-600\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3d163ce\" data-id=\"3d163ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27132a7 elementor-widget elementor-widget-heading\" data-id=\"27132a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Order No: UT 2605<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a27b52 elementor-widget elementor-widget-text-editor\" data-id=\"8a27b52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Material:<\/strong>\u00a0TPU<\/p><p><strong>Lenght:<\/strong>\u00a0200 mm<\/p><p><strong>Width:<\/strong>\u00a030 mm<\/p><p><strong>Height:<\/strong>\u00a0850 mm<\/p><p><strong>Weight:<\/strong>\u00a02,2 kg\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-01ac8e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"01ac8e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-593a6a8\" data-id=\"593a6a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3ee4bf elementor-widget elementor-widget-image\" data-id=\"a3ee4bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/12\/UT-2608-Flexible-Refuge-Signs-600.jpg\" title=\"UT-2608-Flexible-Refuge-Signs-600\" alt=\"UT-2608-Flexible-Refuge-Signs-600\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-12f7cbd\" data-id=\"12f7cbd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbfbded elementor-widget elementor-widget-heading\" data-id=\"dbfbded\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Order No: UT 2608<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-990236a elementor-widget elementor-widget-text-editor\" data-id=\"990236a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Material:<\/strong>\u00a0TPU<\/p><p><strong>Lenght:<\/strong>\u00a0220 mm<\/p><p><strong>Width:<\/strong>\u00a075 mm<\/p><p><strong>Height:<\/strong>\u00a01000 mm<\/p><p><strong>Weight:<\/strong>\u00a02 kg\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-277c75e8\" data-id=\"277c75e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-636c7f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"636c7f8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c0df1bf\" data-id=\"c0df1bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56b6d9e elementor-widget elementor-widget-image\" data-id=\"56b6d9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/12\/UT-2602-Flexible-Refuge-Signs-600.jpg\" title=\"UT-2602-Flexible-Refuge-Signs-600\" alt=\"UT-2602-Flexible-Refuge-Signs-600\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b23d004\" data-id=\"b23d004\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-faa65c3 elementor-widget elementor-widget-heading\" data-id=\"faa65c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Order No: UT 2602<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3685ccf elementor-widget elementor-widget-text-editor\" data-id=\"3685ccf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Material:<\/strong>\u00a0TPU<\/p><p><strong>Lenght:<\/strong>\u00a0200 mm<\/p><p><strong>Width:<\/strong>\u00a030 mm<\/p><p><strong>Height:<\/strong>\u00a0850 mm<\/p><p><strong>Weight:<\/strong>\u00a02 kg\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f416707 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f416707\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3b7d04d\" data-id=\"3b7d04d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-732c4b7 elementor-widget elementor-widget-image\" data-id=\"732c4b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/12\/UT-2607-Flexible-Refuge-Signs-600.jpg\" title=\"UT-2607-Flexible-Refuge-Signs-600\" alt=\"UT-2607-Flexible-Refuge-Signs-600\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-44eea01\" data-id=\"44eea01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bae0531 elementor-widget elementor-widget-heading\" data-id=\"bae0531\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Order No: UT 2607<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-830c24f elementor-widget elementor-widget-text-editor\" data-id=\"830c24f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Material:<\/strong>\u00a0TPU<\/p><p><strong>Lenght:<\/strong>\u00a0315 mm<\/p><p><strong>Width:<\/strong>\u00a040 mm<\/p><p><strong>Height:<\/strong>\u00a01000 mm<\/p><p><strong>Weight:<\/strong>\u00a03,42 kg\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3ea80b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ea80b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c6c36fc\" data-id=\"c6c36fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fefaa20 elementor-widget elementor-widget-image\" data-id=\"fefaa20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/12\/UT-2603-Flexible-Refuge-Signs-600.jpg\" title=\"UT-2603-Flexible-Refuge-Signs-600\" alt=\"UT-2603-Flexible-Refuge-Signs-600\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f474959\" data-id=\"f474959\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c894a58 elementor-widget elementor-widget-heading\" data-id=\"c894a58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Order No: UT 2603<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13c17e5 elementor-widget elementor-widget-text-editor\" data-id=\"13c17e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Material:<\/strong>\u00a0TPU<\/p><p><strong>Lenght:<\/strong>\u00a0220 mm<\/p><p><strong>Width:<\/strong>\u00a075 mm<\/p><p><strong>Height:<\/strong>\u00a01000 mm<\/p><p><strong>Weight:<\/strong>\u00a06 kg\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0f520a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0f520a5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-08487df\" data-id=\"08487df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56541f5 elementor-widget elementor-widget-image\" data-id=\"56541f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/12\/UT-2604-Flexible-Refuge-Signs-600.jpg\" title=\"UT-2604-Flexible-Refuge-Signs-600\" alt=\"UT-2604-Flexible-Refuge-Signs-600\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b821bea\" data-id=\"b821bea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31a26db elementor-widget elementor-widget-heading\" data-id=\"31a26db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Order No: UT 2604<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-837b561 elementor-widget elementor-widget-text-editor\" data-id=\"837b561\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Material:<\/strong>\u00a0TPU<\/p><p><strong>Lenght:<\/strong>\u00a0220 mm<\/p><p><strong>Width:<\/strong>\u00a075 mm<\/p><p><strong>Height:<\/strong>\u00a01000 mm<\/p><p><strong>Weight:<\/strong>\u00a04,24 kg\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2aa62031 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2aa62031\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-62335317\" data-id=\"62335317\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-26f7b026\" data-id=\"26f7b026\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f724559 elementor-widget elementor-widget-heading\" data-id=\"f724559\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Meridian Group's Flexible Refuge Signs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e6f3f90 elementor-widget elementor-widget-text-editor\" data-id=\"2e6f3f90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Flexible refuge signs are primarily used at round about intersections within the splitter islands and at the ends of pedestrian refuge islands, typically located at mid block pedestrian crosswalks. Flexible refuge signs are also used to supplement street signs to provide a visiual cue to approaching drivers that an obstacle exists and to indicate that braking may be required.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3468678 elementor-widget elementor-widget-heading\" data-id=\"3468678\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Flexible Refuge Signs Features:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19ce847f elementor-widget elementor-widget-text-editor\" data-id=\"19ce847f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Extremely flexible TPU material unbreakable and rebound design.<\/li><li>Strong resistance to weather conditions -20 to +60 C.<\/li><li>Easily installed.<\/li><li>Excellent night day visibility.<\/li><li>Extremely high quality of reflective sheeting used. ( PVC tape )<\/li><li>Soft material so as not to damage the vehicle at a collision.<\/li><li>UV stabilized and non-fading colors used.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Fleksibilni Sigurnosni Znak Broj Narud\u017ebe: UT 2601 Materijal:\u00a0TPU Du\u017eina:\u00a0200 mm \u0160irina:\u00a030 mm Visina:\u00a0850 mm Te\u017eina:\u00a02 kg\u00a0 Broj Narud\u017ebe: UT 2606 Materijal:\u00a0TPU Du\u017eina:\u00a0315 mm \u0160irina:\u00a040 mm Visina:\u00a01000 mm Te\u017eina:\u00a03,42 kg\u00a0 Broj Narud\u017ebe: UT 2605 Materijal:\u00a0TPU Du\u017eina:\u00a0200 mm \u0160irina:\u00a030 mm Visina:\u00a0850 mm Te\u017eina:\u00a02,2 kg\u00a0 Broj Narud\u017ebe: UT 2608 Materijal:\u00a0TPU Du\u017eina:\u00a0220 mm \u0160irina:\u00a075 mm Visina:\u00a01000 mm Te\u017eina:\u00a02 kg\u00a0 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7402","page","type-page","status-publish","hentry","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fleksibilni Sigurnosni Znak - Meridian Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meridian.ba\/en\/fleksibilni-sigurnosni-znak\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fleksibilni Sigurnosni Znak - Meridian Group\" \/>\n<meta property=\"og:description\" content=\"Fleksibilni Sigurnosni Znak Broj Narud\u017ebe: UT 2601 Materijal:\u00a0TPU Du\u017eina:\u00a0200 mm \u0160irina:\u00a030 mm Visina:\u00a0850 mm Te\u017eina:\u00a02 kg\u00a0 Broj Narud\u017ebe: UT 2606 Materijal:\u00a0TPU Du\u017eina:\u00a0315 mm \u0160irina:\u00a040 mm Visina:\u00a01000 mm Te\u017eina:\u00a03,42 kg\u00a0 Broj Narud\u017ebe: UT 2605 Materijal:\u00a0TPU Du\u017eina:\u00a0200 mm \u0160irina:\u00a030 mm Visina:\u00a0850 mm Te\u017eina:\u00a02,2 kg\u00a0 Broj Narud\u017ebe: UT 2608 Materijal:\u00a0TPU Du\u017eina:\u00a0220 mm \u0160irina:\u00a075 mm Visina:\u00a01000 mm Te\u017eina:\u00a02 kg\u00a0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meridian.ba\/en\/fleksibilni-sigurnosni-znak\/\" \/>\n<meta property=\"og:site_name\" content=\"Meridian Group\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/meridian.ba\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-09T19:44:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/12\/UT-2601-Flexible-Refuge-Signs-600.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MeridianGroup2\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/en\\\/fleksibilni-sigurnosni-znak\\\/\",\"url\":\"https:\\\/\\\/www.meridian.ba\\\/en\\\/fleksibilni-sigurnosni-znak\\\/\",\"name\":\"Fleksibilni Sigurnosni Znak - Meridian Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/en\\\/fleksibilni-sigurnosni-znak\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/en\\\/fleksibilni-sigurnosni-znak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meridian.ba\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/UT-2601-Flexible-Refuge-Signs-600.jpg\",\"datePublished\":\"2019-12-07T15:18:50+00:00\",\"dateModified\":\"2019-12-09T19:44:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/en\\\/fleksibilni-sigurnosni-znak\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.meridian.ba\\\/en\\\/fleksibilni-sigurnosni-znak\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/en\\\/fleksibilni-sigurnosni-znak\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.meridian.ba\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/UT-2601-Flexible-Refuge-Signs-600.jpg\",\"contentUrl\":\"https:\\\/\\\/www.meridian.ba\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/UT-2601-Flexible-Refuge-Signs-600.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/en\\\/fleksibilni-sigurnosni-znak\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.meridian.ba\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fleksibilni Sigurnosni Znak\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/#website\",\"url\":\"https:\\\/\\\/www.meridian.ba\\\/\",\"name\":\"Meridian Group\",\"description\":\"Rje\u0161enja pakovanja i skladi\u0161tenja\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.meridian.ba\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fleksibilni Sigurnosni Znak - Meridian Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meridian.ba\/en\/fleksibilni-sigurnosni-znak\/","og_locale":"en_US","og_type":"article","og_title":"Fleksibilni Sigurnosni Znak - Meridian Group","og_description":"Fleksibilni Sigurnosni Znak Broj Narud\u017ebe: UT 2601 Materijal:\u00a0TPU Du\u017eina:\u00a0200 mm \u0160irina:\u00a030 mm Visina:\u00a0850 mm Te\u017eina:\u00a02 kg\u00a0 Broj Narud\u017ebe: UT 2606 Materijal:\u00a0TPU Du\u017eina:\u00a0315 mm \u0160irina:\u00a040 mm Visina:\u00a01000 mm Te\u017eina:\u00a03,42 kg\u00a0 Broj Narud\u017ebe: UT 2605 Materijal:\u00a0TPU Du\u017eina:\u00a0200 mm \u0160irina:\u00a030 mm Visina:\u00a0850 mm Te\u017eina:\u00a02,2 kg\u00a0 Broj Narud\u017ebe: UT 2608 Materijal:\u00a0TPU Du\u017eina:\u00a0220 mm \u0160irina:\u00a075 mm Visina:\u00a01000 mm Te\u017eina:\u00a02 kg\u00a0 [&hellip;]","og_url":"https:\/\/www.meridian.ba\/en\/fleksibilni-sigurnosni-znak\/","og_site_name":"Meridian Group","article_publisher":"https:\/\/www.facebook.com\/meridian.ba","article_modified_time":"2019-12-09T19:44:31+00:00","og_image":[{"url":"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/12\/UT-2601-Flexible-Refuge-Signs-600.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@MeridianGroup2","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.meridian.ba\/en\/fleksibilni-sigurnosni-znak\/","url":"https:\/\/www.meridian.ba\/en\/fleksibilni-sigurnosni-znak\/","name":"Fleksibilni Sigurnosni Znak - Meridian Group","isPartOf":{"@id":"https:\/\/www.meridian.ba\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.meridian.ba\/en\/fleksibilni-sigurnosni-znak\/#primaryimage"},"image":{"@id":"https:\/\/www.meridian.ba\/en\/fleksibilni-sigurnosni-znak\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/12\/UT-2601-Flexible-Refuge-Signs-600.jpg","datePublished":"2019-12-07T15:18:50+00:00","dateModified":"2019-12-09T19:44:31+00:00","breadcrumb":{"@id":"https:\/\/www.meridian.ba\/en\/fleksibilni-sigurnosni-znak\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.meridian.ba\/en\/fleksibilni-sigurnosni-znak\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.meridian.ba\/en\/fleksibilni-sigurnosni-znak\/#primaryimage","url":"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/12\/UT-2601-Flexible-Refuge-Signs-600.jpg","contentUrl":"https:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/12\/UT-2601-Flexible-Refuge-Signs-600.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.meridian.ba\/en\/fleksibilni-sigurnosni-znak\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.meridian.ba\/"},{"@type":"ListItem","position":2,"name":"Fleksibilni Sigurnosni Znak"}]},{"@type":"WebSite","@id":"https:\/\/www.meridian.ba\/#website","url":"https:\/\/www.meridian.ba\/","name":"Meridian Group","description":"Rje\u0161enja pakovanja i skladi\u0161tenja","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meridian.ba\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/pages\/7402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/comments?post=7402"}],"version-history":[{"count":0,"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/pages\/7402\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/media?parent=7402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}