{"id":13763,"date":"2020-05-26T18:54:46","date_gmt":"2020-05-26T18:54:46","guid":{"rendered":"https:\/\/www.meridian.ba\/?page_id=13763"},"modified":"2022-04-21T15:44:53","modified_gmt":"2022-04-21T15:44:53","slug":"poligon-radni-stol","status":"publish","type":"page","link":"https:\/\/www.meridian.ba\/en\/poligon-radni-stol\/","title":{"rendered":"Poligon Radni stol"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"13763\" class=\"elementor elementor-13763\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-140d2dca elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"140d2dca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1b746e01\" data-id=\"1b746e01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f222b49 elementor-widget elementor-widget-image\" data-id=\"f222b49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/01\/FerdyItaly.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTUzLCJ1cmwiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/01\/FerdyItaly.jpg\" title=\"\" alt=\"\" class=\"elementor-animation-shrink\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3a13a229\" data-id=\"3a13a229\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-695ddf76 elementor-widget elementor-widget-image\" data-id=\"695ddf76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/01\/AnnaPhotography.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0LCJ1cmwiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/01\/AnnaPhotography.jpg\" title=\"\" alt=\"\" class=\"elementor-animation-shrink\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-12fd4824\" data-id=\"12fd4824\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34dbd972 elementor-widget elementor-widget-image\" data-id=\"34dbd972\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/01\/FerdyCapeTown.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU1LCJ1cmwiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/01\/FerdyCapeTown.jpg\" title=\"\" alt=\"\" class=\"elementor-animation-shrink\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6dc2197e\" data-id=\"6dc2197e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a99de4c elementor-widget elementor-widget-image\" data-id=\"6a99de4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/01\/AnnaItaly.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU2LCJ1cmwiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/01\/AnnaItaly.jpg\" title=\"\" alt=\"\" class=\"elementor-animation-shrink\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cd6c34b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd6c34b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c65c660\" data-id=\"c65c660\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-704ea4e7\" data-id=\"704ea4e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9aa196b elementor-widget elementor-widget-heading\" data-id=\"9aa196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Metal Polygon Workbenches<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5207b0d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5207b0d2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-19d4e64\" data-id=\"19d4e64\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70579a1f elementor-nav-menu__align-start elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"70579a1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-chevron-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-70579a1f\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12995\"><a href=\"https:\/\/www.meridian.ba\/en\/cnc-ormari-za-alat\/\" class=\"elementor-item\">Cnc Tool Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13261\"><a href=\"https:\/\/www.meridian.ba\/en\/industrijski-ormari\/\" class=\"elementor-item\">Industrial Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13292\"><a href=\"https:\/\/www.meridian.ba\/en\/metalni-kancelarijski-ladicar\/\" class=\"elementor-item\">Office Drawer<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13488\"><a href=\"https:\/\/www.meridian.ba\/en\/kolica-za-alat\/\" class=\"elementor-item\">Tool Trolley<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13438\"><a href=\"https:\/\/www.meridian.ba\/en\/metalni-garderobni-ormar-za-opremu\/\" class=\"elementor-item\">Metal Wardrobes<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13358\"><a href=\"https:\/\/www.meridian.ba\/en\/mobilni-radni-stol\/\" class=\"elementor-item\">Mobile Workbenches<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12996\"><a href=\"https:\/\/www.meridian.ba\/en\/metalni-ormari-sa-kliznim-vratima\/\" class=\"elementor-item\">Sliding Door Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-13186\"><a href=\"https:\/\/www.meridian.ba\/en\/ormari-sa-ladicom\/\" class=\"elementor-item\">Drawer Cabinets<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13185\"><a href=\"https:\/\/www.meridian.ba\/en\/serija-1000-ormari-sa-ladicom\/\" class=\"elementor-sub-item\">Series 1000<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13184\"><a href=\"https:\/\/www.meridian.ba\/en\/serija-5000-ormari-sa-ladicom\/\" class=\"elementor-sub-item\">Series 5000<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13181\"><a href=\"https:\/\/www.meridian.ba\/en\/serija-7000-ormari-sa-ladicom\/\" class=\"elementor-sub-item\">Series 7000<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13180\"><a href=\"https:\/\/www.meridian.ba\/en\/serija-10000-ormari-sa-ladicom\/\" class=\"elementor-sub-item\">Series 10000<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13179\"><a href=\"https:\/\/www.meridian.ba\/en\/serija-11000-ormari-sa-ladicom\/\" class=\"elementor-sub-item\">Series 11000<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13183\"><a href=\"https:\/\/www.meridian.ba\/en\/serija-57000-ormari-sa-ladicom\/\" class=\"elementor-sub-item\">Series 57000<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13182\"><a href=\"https:\/\/www.meridian.ba\/en\/serija-75000-ormari-sa-ladicom\/\" class=\"elementor-sub-item\">Series 75000<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13193\"><a href=\"https:\/\/www.meridian.ba\/en\/ormari-za-fajlove\/\" class=\"elementor-item\">Folder Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13264\"><a href=\"https:\/\/www.meridian.ba\/en\/ormari-za-karte\/\" class=\"elementor-item\">Map Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13373\"><a href=\"https:\/\/www.meridian.ba\/en\/metalni-ormar-za-kartoteku\/\" class=\"elementor-item\">File Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13291\"><a href=\"https:\/\/www.meridian.ba\/en\/skladisni-ormari-za-materijal\/\" class=\"elementor-item\">Material Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19330\"><a href=\"https:\/\/www.meridian.ba\/en\/ormari-za-skladistenje-hemikalija\/\" class=\"elementor-item\">Chemical Storage Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13821\"><a href=\"https:\/\/www.meridian.ba\/en\/ormari-za-oruzje\/\" class=\"elementor-item\">Weapon Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13042\"><a href=\"https:\/\/www.meridian.ba\/en\/ormari-za-racunare\/\" class=\"elementor-item\">Computer Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-13789\"><a href=\"https:\/\/www.meridian.ba\/en\/radni-stolovi\/\" class=\"elementor-item\">Workbenches<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13788\"><a href=\"https:\/\/www.meridian.ba\/en\/ambalazni-radni-stolovi\/\" class=\"elementor-sub-item\">Packaging Workbenches<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13786\"><a href=\"https:\/\/www.meridian.ba\/en\/esd-radni-stol\/\" class=\"elementor-sub-item\">ESD Workbenches<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13785\"><a href=\"https:\/\/www.meridian.ba\/en\/mali-radni-stol\/\" class=\"elementor-sub-item\">Small Workbenches<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13787\"><a href=\"https:\/\/www.meridian.ba\/en\/metalni-radni-stol\/\" class=\"elementor-sub-item\">Metal Workbenches<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13782\"><a href=\"https:\/\/www.meridian.ba\/en\/poligon-radni-stol\/\" class=\"elementor-sub-item\">Polygon Workbenches<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13784\"><a href=\"https:\/\/www.meridian.ba\/en\/radni-stolovi-sa-panelom-za-alat\/\" class=\"elementor-sub-item\">Workbenches with Tool Panel<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13783\"><a href=\"https:\/\/www.meridian.ba\/en\/radni-stol-za-poslovodje-i-supervizore\/\" class=\"elementor-sub-item\">Office Desks<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13384\"><a href=\"https:\/\/www.meridian.ba\/en\/bezbjedni-ormari\/\" class=\"elementor-item\">Safety Cabinets<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-70579a1f\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12995\"><a href=\"https:\/\/www.meridian.ba\/en\/cnc-ormari-za-alat\/\" class=\"elementor-item\" tabindex=\"-1\">Cnc Tool Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13261\"><a href=\"https:\/\/www.meridian.ba\/en\/industrijski-ormari\/\" class=\"elementor-item\" tabindex=\"-1\">Industrial Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13292\"><a href=\"https:\/\/www.meridian.ba\/en\/metalni-kancelarijski-ladicar\/\" class=\"elementor-item\" tabindex=\"-1\">Office Drawer<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13488\"><a href=\"https:\/\/www.meridian.ba\/en\/kolica-za-alat\/\" class=\"elementor-item\" tabindex=\"-1\">Tool Trolley<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13438\"><a href=\"https:\/\/www.meridian.ba\/en\/metalni-garderobni-ormar-za-opremu\/\" class=\"elementor-item\" tabindex=\"-1\">Metal Wardrobes<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13358\"><a href=\"https:\/\/www.meridian.ba\/en\/mobilni-radni-stol\/\" class=\"elementor-item\" tabindex=\"-1\">Mobile Workbenches<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12996\"><a href=\"https:\/\/www.meridian.ba\/en\/metalni-ormari-sa-kliznim-vratima\/\" class=\"elementor-item\" tabindex=\"-1\">Sliding Door Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-13186\"><a href=\"https:\/\/www.meridian.ba\/en\/ormari-sa-ladicom\/\" class=\"elementor-item\" tabindex=\"-1\">Drawer Cabinets<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13185\"><a href=\"https:\/\/www.meridian.ba\/en\/serija-1000-ormari-sa-ladicom\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Series 1000<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13184\"><a href=\"https:\/\/www.meridian.ba\/en\/serija-5000-ormari-sa-ladicom\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Series 5000<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13181\"><a href=\"https:\/\/www.meridian.ba\/en\/serija-7000-ormari-sa-ladicom\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Series 7000<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13180\"><a href=\"https:\/\/www.meridian.ba\/en\/serija-10000-ormari-sa-ladicom\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Series 10000<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13179\"><a href=\"https:\/\/www.meridian.ba\/en\/serija-11000-ormari-sa-ladicom\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Series 11000<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13183\"><a href=\"https:\/\/www.meridian.ba\/en\/serija-57000-ormari-sa-ladicom\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Series 57000<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13182\"><a href=\"https:\/\/www.meridian.ba\/en\/serija-75000-ormari-sa-ladicom\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Series 75000<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13193\"><a href=\"https:\/\/www.meridian.ba\/en\/ormari-za-fajlove\/\" class=\"elementor-item\" tabindex=\"-1\">Folder Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13264\"><a href=\"https:\/\/www.meridian.ba\/en\/ormari-za-karte\/\" class=\"elementor-item\" tabindex=\"-1\">Map Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13373\"><a href=\"https:\/\/www.meridian.ba\/en\/metalni-ormar-za-kartoteku\/\" class=\"elementor-item\" tabindex=\"-1\">File Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13291\"><a href=\"https:\/\/www.meridian.ba\/en\/skladisni-ormari-za-materijal\/\" class=\"elementor-item\" tabindex=\"-1\">Material Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19330\"><a href=\"https:\/\/www.meridian.ba\/en\/ormari-za-skladistenje-hemikalija\/\" class=\"elementor-item\" tabindex=\"-1\">Chemical Storage Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13821\"><a href=\"https:\/\/www.meridian.ba\/en\/ormari-za-oruzje\/\" class=\"elementor-item\" tabindex=\"-1\">Weapon Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13042\"><a href=\"https:\/\/www.meridian.ba\/en\/ormari-za-racunare\/\" class=\"elementor-item\" tabindex=\"-1\">Computer Cabinets<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-13789\"><a href=\"https:\/\/www.meridian.ba\/en\/radni-stolovi\/\" class=\"elementor-item\" tabindex=\"-1\">Workbenches<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13788\"><a href=\"https:\/\/www.meridian.ba\/en\/ambalazni-radni-stolovi\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Packaging Workbenches<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13786\"><a href=\"https:\/\/www.meridian.ba\/en\/esd-radni-stol\/\" class=\"elementor-sub-item\" tabindex=\"-1\">ESD Workbenches<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13785\"><a href=\"https:\/\/www.meridian.ba\/en\/mali-radni-stol\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Small Workbenches<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13787\"><a href=\"https:\/\/www.meridian.ba\/en\/metalni-radni-stol\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Metal Workbenches<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13782\"><a href=\"https:\/\/www.meridian.ba\/en\/poligon-radni-stol\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Polygon Workbenches<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13784\"><a href=\"https:\/\/www.meridian.ba\/en\/radni-stolovi-sa-panelom-za-alat\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Workbenches with Tool Panel<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13783\"><a href=\"https:\/\/www.meridian.ba\/en\/radni-stol-za-poslovodje-i-supervizore\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Office Desks<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13384\"><a href=\"https:\/\/www.meridian.ba\/en\/bezbjedni-ormari\/\" class=\"elementor-item\" tabindex=\"-1\">Safety Cabinets<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-68b30d6b\" data-id=\"68b30d6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-45d7a3d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45d7a3d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5a29afe0\" data-id=\"5a29afe0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a20557b elementor-widget elementor-widget-image\" data-id=\"6a20557b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2020\/05\/Metalni-poligon-radni-stol-3805.jpg\" title=\"Metalni-poligon-radni-stol-3805\" alt=\"\u0160esterokutni Radni stol\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Model No 3805<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-78278a9e\" data-id=\"78278a9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35b66c0e elementor-widget elementor-widget-heading\" data-id=\"35b66c0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hexagonal Workbench with 9 Drawers<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14640e53 elementor-widget elementor-widget-text-editor\" data-id=\"14640e53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Width: 1830 mm<br \/>Depth: 1585 mm<br \/>Height: 850 mm<br \/>Color: Ral 5015<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-198b505 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"198b505\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f5aaaf7\" data-id=\"f5aaaf7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f3d96c elementor-widget elementor-widget-image\" data-id=\"8f3d96c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2020\/05\/Metalni-poligon-radni-stol-3820.jpg\" title=\"Metalni-poligon-radni-stol-3820\" alt=\"\u0160esterokutni Radni stol\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Model No 3820<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d8042d4\" data-id=\"d8042d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-854aa9a elementor-widget elementor-widget-heading\" data-id=\"854aa9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hexagonal Workbench With 3 Drawers and 3 Cabinets<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00dc76b elementor-widget elementor-widget-text-editor\" data-id=\"00dc76b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Width: 1830 mm<br \/>Depth: 1585 mm<br \/>Height: 850 mm<br \/>Color: Ral 5015<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-90433d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"90433d2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-edd812a\" data-id=\"edd812a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61c2863 elementor-widget elementor-widget-image\" data-id=\"61c2863\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2020\/05\/Metalni-poligon-radni-stol-3835.jpg\" title=\"Metalni-poligon-radni-stol-3835\" alt=\"Osmerokutni Radni stol\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Model No 3835<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-717f37f\" data-id=\"717f37f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a934cd7 elementor-widget elementor-widget-heading\" data-id=\"a934cd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Octagonal Workbench with 4 Drawers<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41553f3 elementor-widget elementor-widget-text-editor\" data-id=\"41553f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Width: 1830 mm<br \/>Depth: 1830 mm<br \/>Height: 850 mm<br \/>Color: Ral 5015<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-363c557 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"363c557\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-27be0a1\" data-id=\"27be0a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef19b5f elementor-widget elementor-widget-image\" data-id=\"ef19b5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2020\/05\/Metalni-poligon-radni-stol-3855.jpg\" title=\"Metalni-poligon-radni-stol-3855\" alt=\"Osmerokutni Radni stol\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Model No 3855<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-427bdd1\" data-id=\"427bdd1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b22b36 elementor-widget elementor-widget-heading\" data-id=\"1b22b36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Octagonal Workbench with 8 Drawers<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5c86bd elementor-widget elementor-widget-text-editor\" data-id=\"b5c86bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Width: 1830 mm<br \/>Depth: 1830 mm<br \/>Height: 850 mm<br \/>Color: Ral 5015<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-029bb09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"029bb09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-eb53bfb\" data-id=\"eb53bfb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8e8922 elementor-widget elementor-widget-image\" data-id=\"f8e8922\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2020\/05\/Metalni-poligon-radni-stol-3870.jpg\" title=\"Metalni-poligon-radni-stol-3870\" alt=\"Osmerokutni Radni stol\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Model No 3870<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ee20edf\" data-id=\"ee20edf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cc6a8d elementor-widget elementor-widget-heading\" data-id=\"7cc6a8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Octagonal Workbench<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b404dc4 elementor-widget elementor-widget-text-editor\" data-id=\"b404dc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Width: 1830 mm<br \/>Depth: 1830 mm<br \/>Height: 850 mm<br \/>Color: Ral 5015<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-36f86ce0\" data-id=\"36f86ce0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6a3ef037 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a3ef037\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-918fd62\" data-id=\"918fd62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fc0651 elementor-widget elementor-widget-image\" data-id=\"3fc0651\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2020\/05\/Metalni-poligon-radni-stol-3815.jpg\" title=\"Metalni-poligon-radni-stol-3815\" alt=\"Osmerokutni Radni stol\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Model No 3815<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-782782\" data-id=\"782782\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dcf2c2b elementor-widget elementor-widget-heading\" data-id=\"3dcf2c2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Octagonal Workbench with 16 Drawers<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-408538c2 elementor-widget elementor-widget-text-editor\" data-id=\"408538c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Width: 1830 mm<br \/>Depth: 1830 mm<br \/>Height: 850 mm<br \/>Color: Ral 5015<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-344e7ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"344e7ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ac1494e\" data-id=\"ac1494e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4e9b2f elementor-widget elementor-widget-image\" data-id=\"e4e9b2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2020\/05\/Metalni-poligon-radni-stol-3825.jpg\" title=\"Metalni-poligon-radni-stol-3825\" alt=\"\u0160esterokutni Radni stol\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Model No 3825<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-148c38b\" data-id=\"148c38b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a21044a elementor-widget elementor-widget-heading\" data-id=\"a21044a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hexagonal Workbench With 3 Lower Shelves<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f23bd7 elementor-widget elementor-widget-text-editor\" data-id=\"0f23bd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Width: 1830 mm<br \/>Depth: 1830 mm<br \/>Height: 850 mm<br \/>Color: Ral 5015<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ec4f260 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec4f260\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-199c90a\" data-id=\"199c90a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17c2e3c elementor-widget elementor-widget-image\" data-id=\"17c2e3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2020\/05\/Metalni-poligon-radni-stol-3840.jpg\" title=\"Metalni-poligon-radni-stol-3840\" alt=\"\u0160esterokutni Radni stol\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Model No 3840<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3c1de86\" data-id=\"3c1de86\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5840c0e elementor-widget elementor-widget-heading\" data-id=\"5840c0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hexagonal Workbench with 15 Drawers<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-130daee elementor-widget elementor-widget-text-editor\" data-id=\"130daee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Width: 1830 mm<br \/>Depth: 1830 mm<br \/>Height: 850 mm<br \/>Color: Ral 5015<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b84b437 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b84b437\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e22d8e7\" data-id=\"e22d8e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-efc6b56 elementor-widget elementor-widget-image\" data-id=\"efc6b56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2020\/05\/Metalni-poligon-radni-stol-3860.jpg\" title=\"Metalni-poligon-radni-stol-3860\" alt=\"\u0160esterokutni Radni stol\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Model No 3860<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-58d5e6a\" data-id=\"58d5e6a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29aa6d3 elementor-widget elementor-widget-heading\" data-id=\"29aa6d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hexagonal Workbench<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f79c83 elementor-widget elementor-widget-text-editor\" data-id=\"6f79c83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Width: 1830 mm<br \/>Depth: 1830 mm<br \/>Height: 850 mm<br \/>Color: Ral 5015<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4933b7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4933b7c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-442e829\" data-id=\"442e829\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09923e0 elementor-widget elementor-widget-image\" data-id=\"09923e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2020\/05\/Metalni-poligon-radni-stol-3875.jpg\" title=\"Metalni-poligon-radni-stol-3875\" alt=\"\u0160esterokutni Radni stol\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Model No 3875<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c0d6431\" data-id=\"c0d6431\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4937250 elementor-widget elementor-widget-heading\" data-id=\"4937250\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0160esterokutni Radni stol sa 3 Ladice<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5355ddb elementor-widget elementor-widget-text-editor\" data-id=\"5355ddb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Width: 1830 mm<br \/>Depth: 1830 mm<br \/>Height: 850 mm<br \/>Color: Ral 5015<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bf4c000 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bf4c000\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5ca1ffaa\" data-id=\"5ca1ffaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5f8d0bb4\" data-id=\"5f8d0bb4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7237d0b3 elementor-widget elementor-widget-heading\" data-id=\"7237d0b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Metalni Poligon Radni Stolovi Meridian Groupe<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d6d0ab8 elementor-widget elementor-widget-text-editor\" data-id=\"5d6d0ab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Metal Polygon Workbenches are suitable for installation, servicing, repair, production in factories, workshops, all types of companies that require craftsmanship.<\/p><p>It is coated with electrostatic powder. Drawer combinations can be made as desired. Hanging plate, electric panel, fluorescent bulbs can be added to desks. The profile frame is 50x50x1.5 mm. The upper surface is made of 25 mm MDF, coated with pinotex and the upper part of the table can consist of rubber board, galvanized board and stainless steel board. Rubber plates are connected with MDF galvanized L strips. The legs are welded and the middle parts are connected with screws. The feet have rubber wheels to prevent scratching and slipping on the floor.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-524121e elementor-widget elementor-widget-image\" data-id=\"524121e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"700\" height=\"716\" src=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2020\/05\/Metalni-poligon-radni-stolovi.jpg\" class=\"attachment-large size-large wp-image-13779\" alt=\"\" srcset=\"https:\/\/www.meridian.ba\/wp-content\/uploads\/2020\/05\/Metalni-poligon-radni-stolovi.jpg 700w, https:\/\/www.meridian.ba\/wp-content\/uploads\/2020\/05\/Metalni-poligon-radni-stolovi-293x300.jpg 293w, https:\/\/www.meridian.ba\/wp-content\/uploads\/2020\/05\/Metalni-poligon-radni-stolovi-600x614.jpg 600w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Metalni Poligon Radni Stolovi Broj Modela 3805 \u0160esterokutni Radni stol sa 9 Ladica \u0160irina: 1830 mmDubina: 1585 mmVisina: 850 mmBoja: Ral 5015 Broj Modela 3820 \u0160esterokutni Radni stol Sa 3 Ladice i 3 Ormari\u0107a \u0160irina: 1830 mmDubina: 1585 mmVisina: 850 mmBoja: Ral 5015 Broj Modela 3835 Osmerokutni Radni stol Sa 4 Ladica \u0160irina: 1830 mmDubina: [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13763","page","type-page","status-publish","hentry","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Poligon Radni stol - Meridian Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meridian.ba\/en\/poligon-radni-stol\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Poligon Radni stol - Meridian Group\" \/>\n<meta property=\"og:description\" content=\"Metalni Poligon Radni Stolovi Broj Modela 3805 \u0160esterokutni Radni stol sa 9 Ladica \u0160irina: 1830 mmDubina: 1585 mmVisina: 850 mmBoja: Ral 5015 Broj Modela 3820 \u0160esterokutni Radni stol Sa 3 Ladice i 3 Ormari\u0107a \u0160irina: 1830 mmDubina: 1585 mmVisina: 850 mmBoja: Ral 5015 Broj Modela 3835 Osmerokutni Radni stol Sa 4 Ladica \u0160irina: 1830 mmDubina: [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meridian.ba\/en\/poligon-radni-stol\/\" \/>\n<meta property=\"og:site_name\" content=\"Meridian Group\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/meridian.ba\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-21T15:44:53+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/01\/FerdyItaly.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MeridianGroup2\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/poligon-radni-stol\\\/\",\"url\":\"https:\\\/\\\/www.meridian.ba\\\/poligon-radni-stol\\\/\",\"name\":\"Poligon Radni stol - Meridian Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/poligon-radni-stol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/poligon-radni-stol\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.meridian.ba\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/FerdyItaly.jpg\",\"datePublished\":\"2020-05-26T18:54:46+00:00\",\"dateModified\":\"2022-04-21T15:44:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/poligon-radni-stol\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.meridian.ba\\\/poligon-radni-stol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/poligon-radni-stol\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.meridian.ba\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/FerdyItaly.jpg\",\"contentUrl\":\"http:\\\/\\\/www.meridian.ba\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/FerdyItaly.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/poligon-radni-stol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.meridian.ba\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Poligon Radni stol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.meridian.ba\\\/#website\",\"url\":\"https:\\\/\\\/www.meridian.ba\\\/\",\"name\":\"Meridian Group\",\"description\":\"Rje\u0161enja pakovanja i skladi\u0161tenja\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.meridian.ba\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Poligon Radni stol - Meridian Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meridian.ba\/en\/poligon-radni-stol\/","og_locale":"en_US","og_type":"article","og_title":"Poligon Radni stol - Meridian Group","og_description":"Metalni Poligon Radni Stolovi Broj Modela 3805 \u0160esterokutni Radni stol sa 9 Ladica \u0160irina: 1830 mmDubina: 1585 mmVisina: 850 mmBoja: Ral 5015 Broj Modela 3820 \u0160esterokutni Radni stol Sa 3 Ladice i 3 Ormari\u0107a \u0160irina: 1830 mmDubina: 1585 mmVisina: 850 mmBoja: Ral 5015 Broj Modela 3835 Osmerokutni Radni stol Sa 4 Ladica \u0160irina: 1830 mmDubina: [&hellip;]","og_url":"https:\/\/www.meridian.ba\/en\/poligon-radni-stol\/","og_site_name":"Meridian Group","article_publisher":"https:\/\/www.facebook.com\/meridian.ba","article_modified_time":"2022-04-21T15:44:53+00:00","og_image":[{"url":"http:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/01\/FerdyItaly.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@MeridianGroup2","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.meridian.ba\/poligon-radni-stol\/","url":"https:\/\/www.meridian.ba\/poligon-radni-stol\/","name":"Poligon Radni stol - Meridian Group","isPartOf":{"@id":"https:\/\/www.meridian.ba\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.meridian.ba\/poligon-radni-stol\/#primaryimage"},"image":{"@id":"https:\/\/www.meridian.ba\/poligon-radni-stol\/#primaryimage"},"thumbnailUrl":"http:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/01\/FerdyItaly.jpg","datePublished":"2020-05-26T18:54:46+00:00","dateModified":"2022-04-21T15:44:53+00:00","breadcrumb":{"@id":"https:\/\/www.meridian.ba\/poligon-radni-stol\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.meridian.ba\/poligon-radni-stol\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.meridian.ba\/poligon-radni-stol\/#primaryimage","url":"http:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/01\/FerdyItaly.jpg","contentUrl":"http:\/\/www.meridian.ba\/wp-content\/uploads\/2019\/01\/FerdyItaly.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.meridian.ba\/poligon-radni-stol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.meridian.ba\/"},{"@type":"ListItem","position":2,"name":"Poligon Radni stol"}]},{"@type":"WebSite","@id":"https:\/\/www.meridian.ba\/#website","url":"https:\/\/www.meridian.ba\/","name":"Meridian Group","description":"Rje\u0161enja pakovanja i skladi\u0161tenja","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meridian.ba\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/pages\/13763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/comments?post=13763"}],"version-history":[{"count":3,"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/pages\/13763\/revisions"}],"predecessor-version":[{"id":19465,"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/pages\/13763\/revisions\/19465"}],"wp:attachment":[{"href":"https:\/\/www.meridian.ba\/en\/wp-json\/wp\/v2\/media?parent=13763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}